{"id":18558,"date":"2023-10-28T13:54:36","date_gmt":"2023-10-28T11:54:36","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=18558"},"modified":"2023-10-31T17:31:52","modified_gmt":"2023-10-31T15:31:52","slug":"descanse-en-paz-loli-que-tenia-el-oficio-mas-bonito-del-mundo-contar-cuentos-a-los-ninos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2023\/10\/descanse-en-paz-loli-que-tenia-el-oficio-mas-bonito-del-mundo-contar-cuentos-a-los-ninos\/","title":{"rendered":"Descanse en paz Loli, que ten\u00eda el oficio m\u00e1s bonito del mundo: contar cuentos a los ni\u00f1os"},"content":{"rendered":"<figure id=\"attachment_8951\" aria-describedby=\"caption-attachment-8951\" style=\"width: 624px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/08\/Emil.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8951\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/08\/Emil.jpeg\" alt=\"\" width=\"624\" height=\"624\" \/><\/a><figcaption id=\"caption-attachment-8951\" class=\"wp-caption-text\">ideal.es<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. No la conoc\u00eda personalmente y bien que lo siento. Ha muerto Loli, que ten\u00eda el oficio m\u00e1s bonito del mundo: contar cuentos a los ni\u00f1os. Lo hac\u00eda en el colegio Al-Zawiya de La Zubia, en Granada. Era una de esas personas imprescindibles.\u00a0 Descanse en paz Loli. Gracias por todo y un abrazo y un beso para su familia . Hasta los que nunca te conocimos, te echaremos de menos.<\/p>\n<p><a href=\"https:\/\/www.ideal.es\/granada\/area-metropolitana\/zubia-llora-loli-cuentacuentos-colegio-alzawiya-capacidad-20231027200358-nt.html\">https:\/\/www.ideal.es\/granada\/area-metropolitana\/zubia-llora-loli-cuentacuentos-colegio-alzawiya-capacidad-20231027200358-nt.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenas, soy Emilio Calatayud. No la conoc\u00eda personalmente y bien que lo siento. Ha muerto Loli, que ten\u00eda el oficio m\u00e1s bonito del mundo: contar cuentos a los ni\u00f1os. Lo hac\u00eda en el colegio Al-Zawiya de La Zubia, en Granada. Era una de esas personas imprescindibles.\u00a0 Descanse en paz Loli. Gracias por todo y un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[3565,3566,3564],"class_list":["post-18558","post","type-post","status-publish","format-standard","hentry","tag-cuenta","tag-cuentos","tag-loli"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-4Pk","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/18558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=18558"}],"version-history":[{"count":5,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/18558\/revisions"}],"predecessor-version":[{"id":18585,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/18558\/revisions\/18585"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=18558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=18558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=18558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}