{"id":17849,"date":"2023-05-27T19:16:29","date_gmt":"2023-05-27T17:16:29","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=17849"},"modified":"2023-05-27T19:16:29","modified_gmt":"2023-05-27T17:16:29","slug":"estoy-reflexionando-para-las-elecciones-pero-pienso-que-deberiamos-reflexionar-todos-los-dias-nos-iria-mejor","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2023\/05\/estoy-reflexionando-para-las-elecciones-pero-pienso-que-deberiamos-reflexionar-todos-los-dias-nos-iria-mejor\/","title":{"rendered":"Estoy reflexionando para las elecciones, pero pienso que deber\u00edamos reflexionar todos los d\u00edas, nos ir\u00eda mejor"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_13866\" aria-describedby=\"caption-attachment-13866\" style=\"width: 3500px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/11\/Emilio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13866\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/11\/Emilio.jpg\" alt=\"\" width=\"3500\" height=\"2333\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/11\/Emilio.jpg 3500w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/11\/Emilio-300x200.jpg 300w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/11\/Emilio-768x512.jpg 768w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/11\/Emilio-644x429.jpg 644w\" sizes=\"auto, (max-width: 3500px) 100vw, 3500px\" \/><\/a><figcaption id=\"caption-attachment-13866\" class=\"wp-caption-text\">Foto: Ram\u00f3n L. P\u00e9rez<\/p>\n<p><\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. Estamos en la jornada de reflexi\u00f3n para las votaciones de este domingo 28 de mayo. As\u00ed que no dir\u00e9 nada que rompa vuestra meditaci\u00f3n ni la m\u00eda.\u00a0 Y all\u00e1 cada uno con sus &#8216;caun\u00e1s&#8217;, como decimos en Gran\u00e1.<\/p>\n<p>En realidad, pienso que deber\u00edamos reflexionar todos los d\u00edas, dedicar aunque sea solo unos minutos a esa tarea tan sana. Nos ir\u00eda mejor. Estoy convencido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. Estamos en la jornada de reflexi\u00f3n para las votaciones de este domingo 28 de mayo. As\u00ed que no dir\u00e9 nada que rompa vuestra meditaci\u00f3n ni la m\u00eda.\u00a0 Y all\u00e1 cada uno con sus &#8216;caun\u00e1s&#8217;, como decimos en Gran\u00e1. En realidad, pienso que deber\u00edamos reflexionar todos los d\u00edas, dedicar aunque sea [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[793,2518],"class_list":["post-17849","post","type-post","status-publish","format-standard","hentry","tag-elecciones","tag-reflexion"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-4DT","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/17849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=17849"}],"version-history":[{"count":5,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/17849\/revisions"}],"predecessor-version":[{"id":17854,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/17849\/revisions\/17854"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=17849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=17849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=17849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}