{"id":17102,"date":"2022-12-05T19:57:33","date_gmt":"2022-12-05T17:57:33","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=17102"},"modified":"2022-12-05T19:57:33","modified_gmt":"2022-12-05T17:57:33","slug":"escuchar-a-los-hijos-y-aprender-de-ellos-tambien-es-educarlos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2022\/12\/escuchar-a-los-hijos-y-aprender-de-ellos-tambien-es-educarlos\/","title":{"rendered":"Escuchar a los hijos y aprender de ellos tambi\u00e9n es educarlos"},"content":{"rendered":"<figure id=\"attachment_8713\" aria-describedby=\"caption-attachment-8713\" style=\"width: 575px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/06\/Notas-emi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8713 size-full\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/06\/Notas-emi.jpg\" alt=\"\" width=\"575\" height=\"323\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/06\/Notas-emi.jpg 575w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/06\/Notas-emi-300x169.jpg 300w\" sizes=\"auto, (max-width: 575px) 100vw, 575px\" \/><\/a><figcaption id=\"caption-attachment-8713\" class=\"wp-caption-text\">xlsemanal.co<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. Durante varios veranos, mi familia y pas\u00e1bamos juntos las vacaciones en una autocaravana. Mis hijos ya eran adolescentes y dedic\u00e1bamos mucho tiempo a hablar. No ten\u00edamos tele ni exist\u00edan los m\u00f3viles. Y los padres aprendimos de ellos. Ten\u00edan otros intereses y otras miradas y nos abrieron los ojos en algunas cosas. En otras no, claro.<\/p>\n<p>Lo que quiero decir es que escuchar a los hijos y aprender de ellos tambi\u00e9n es educarlos. Si est\u00e1is de vacaciones con ellos en estos d\u00edas, aprovechad el tiempo para conoceros.<\/p>\n<p>Por cierto, tambi\u00e9n escucho y aprendo de mis &#8216;choricillos\u00a1. Todos los d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenas, soy Emilio Calatayud. Durante varios veranos, mi familia y pas\u00e1bamos juntos las vacaciones en una autocaravana. Mis hijos ya eran adolescentes y dedic\u00e1bamos mucho tiempo a hablar. No ten\u00edamos tele ni exist\u00edan los m\u00f3viles. Y los padres aprendimos de ellos. Ten\u00edan otros intereses y otras miradas y nos abrieron los ojos en algunas cosas. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[1194,635,2430],"class_list":["post-17102","post","type-post","status-publish","format-standard","hentry","tag-aprender","tag-de","tag-los-hijos"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-4rQ","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/17102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=17102"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/17102\/revisions"}],"predecessor-version":[{"id":17103,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/17102\/revisions\/17103"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=17102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=17102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=17102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}