{"id":16631,"date":"2022-08-12T20:20:57","date_gmt":"2022-08-12T18:20:57","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=16631"},"modified":"2022-08-12T20:20:57","modified_gmt":"2022-08-12T18:20:57","slug":"han-apunalado-a-salman-rushdie-por-un-libro-unos-condenamos-a-escribir-y-otros-condenan-a-los-que-escriben","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2022\/08\/han-apunalado-a-salman-rushdie-por-un-libro-unos-condenamos-a-escribir-y-otros-condenan-a-los-que-escriben\/","title":{"rendered":"Han apu\u00f1alado a Salman Rushdie por un libro, unos condenamos a escribir y otros condenan a los que escriben"},"content":{"rendered":"<p><a href=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Corbata.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9176 size-full\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Corbata.jpg\" alt=\"\" width=\"620\" height=\"349\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Corbata.jpg 620w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Corbata-300x169.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p>Buenas, soy Emilio Calatayud. Me ha impresionado la noticia de que han apu\u00f1alado al escritor Salman Rushdie, que llevaba m\u00e1s de treinta a\u00f1os amenazado de muerte por fan\u00e1ticos. Casi todos nos hab\u00edamos olvidado de \u00e9l, salvo los que lo quieren matar. Y todo por escribir un libro. Unos condenamos a leer\u00a0 y escribir y otros condenan a los que leen y escriben. Pido a Dios y a la ciencia que se recupere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenas, soy Emilio Calatayud. Me ha impresionado la noticia de que han apu\u00f1alado al escritor Salman Rushdie, que llevaba m\u00e1s de treinta a\u00f1os amenazado de muerte por fan\u00e1ticos. Casi todos nos hab\u00edamos olvidado de \u00e9l, salvo los que lo quieren matar. Y todo por escribir un libro. Unos condenamos a leer\u00a0 y escribir y otros [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[3248,3247],"class_list":["post-16631","post","type-post","status-publish","format-standard","hentry","tag-apunalado","tag-salman-rushdie"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-4kf","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/16631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=16631"}],"version-history":[{"count":5,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/16631\/revisions"}],"predecessor-version":[{"id":16636,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/16631\/revisions\/16636"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=16631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=16631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=16631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}