{"id":16624,"date":"2022-08-10T20:17:58","date_gmt":"2022-08-10T18:17:58","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=16624"},"modified":"2022-08-10T20:17:58","modified_gmt":"2022-08-10T18:17:58","slug":"los-ninos-y-los-maestros-pasan-los-inviernos-a-15-grados-y-el-final-de-curso-a-35-a-ver-si-les-ponen-los-19-y-los-27","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2022\/08\/los-ninos-y-los-maestros-pasan-los-inviernos-a-15-grados-y-el-final-de-curso-a-35-a-ver-si-les-ponen-los-19-y-los-27\/","title":{"rendered":"Los ni\u00f1os y los maestros pasan los inviernos a 15 grados y el final de curso, a 35, a ver si les ponen los 19 y los 27"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_11820\" aria-describedby=\"caption-attachment-11820\" style=\"width: 644px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/12\/Emil-neuf.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11820 size-large\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/12\/Emil-neuf-644x429.jpg\" alt=\"\" width=\"644\" height=\"429\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/12\/Emil-neuf-644x429.jpg 644w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/12\/Emil-neuf-300x200.jpg 300w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/12\/Emil-neuf-768x512.jpg 768w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/a><figcaption id=\"caption-attachment-11820\" class=\"wp-caption-text\">Foto: Alfredo Aguilar<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. Ahora que se habla tanto de fijar las temperaturas para ahorrar energ\u00eda, me viene a la cabeza que nuestros ni\u00f1os y los maestros pasan los inviernos a 15 grados y el final del curso, a 35 o m\u00e1s. Pues nada, ya que las temperaturas reglamentarias son 19 y 27 pues a ver si llegan a los colegios. Lo agradecer\u00e1n seguro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. Ahora que se habla tanto de fijar las temperaturas para ahorrar energ\u00eda, me viene a la cabeza que nuestros ni\u00f1os y los maestros pasan los inviernos a 15 grados y el final del curso, a 35 o m\u00e1s. Pues nada, ya que las temperaturas reglamentarias son 19 y 27 pues [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[1557,41,3246],"class_list":["post-16624","post","type-post","status-publish","format-standard","hentry","tag-maestras","tag-ninos","tag-temperaturas"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-4k8","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/16624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=16624"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/16624\/revisions"}],"predecessor-version":[{"id":16627,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/16624\/revisions\/16627"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=16624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=16624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=16624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}