{"id":15725,"date":"2021-12-12T21:03:56","date_gmt":"2021-12-12T19:03:56","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=15725"},"modified":"2021-12-12T21:03:56","modified_gmt":"2021-12-12T19:03:56","slug":"gracias-al-pintor-antonio-lopez-por-esta-frase-si-espana-no-es-mejor-es-porque-somos-tontos-unos-mas-que-otros","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2021\/12\/gracias-al-pintor-antonio-lopez-por-esta-frase-si-espana-no-es-mejor-es-porque-somos-tontos-unos-mas-que-otros\/","title":{"rendered":"Gracias al pintor Antonio L\u00f3pez por esta frase: \u00abSi Espa\u00f1a no es mejor es porque somos tontos. Unos m\u00e1s que otros\u00bb"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_15604\" aria-describedby=\"caption-attachment-15604\" style=\"width: 644px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-15604\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2021\/11\/MIlio-1-644x429.jpg\" alt=\"\" width=\"644\" height=\"429\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2021\/11\/MIlio-1-644x429.jpg 644w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2021\/11\/MIlio-1-300x200.jpg 300w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2021\/11\/MIlio-1-768x512.jpg 768w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2021\/11\/MIlio-1.jpg 1374w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><figcaption id=\"caption-attachment-15604\" class=\"wp-caption-text\">Foto: Pepe Mar\u00edn<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. Para acabar el fin de semana como Dios manda, aqu\u00ed os dejo una reflexi\u00f3n del gran pintor Antonio L\u00f3pez\u00a0 sacada de una entrevista en la revista XL Semanal: \u00abSi Espa\u00f1a no es es mejor es porque somos tontos. Unos m\u00e1s que otros\u00bb.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. Para acabar el fin de semana como Dios manda, aqu\u00ed os dejo una reflexi\u00f3n del gran pintor Antonio L\u00f3pez\u00a0 sacada de una entrevista en la revista XL Semanal: \u00abSi Espa\u00f1a no es es mejor es porque somos tontos. Unos m\u00e1s que otros\u00bb. &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[3061,828,2518],"class_list":["post-15725","post","type-post","status-publish","format-standard","hentry","category-blog","tag-antonio-lopez","tag-pintor","tag-reflexion"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-45D","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/15725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=15725"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/15725\/revisions"}],"predecessor-version":[{"id":15727,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/15725\/revisions\/15727"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=15725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=15725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=15725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}