{"id":15139,"date":"2021-07-31T19:25:52","date_gmt":"2021-07-31T17:25:52","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=15139"},"modified":"2021-07-31T19:25:52","modified_gmt":"2021-07-31T17:25:52","slug":"seria-capaz-quien-defiende-el-ojo-por-ojo-de-matar-a-un-nino-que-ha-matado","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2021\/07\/seria-capaz-quien-defiende-el-ojo-por-ojo-de-matar-a-un-nino-que-ha-matado\/","title":{"rendered":"\u00bfSer\u00eda capaz quien defiende el ojo por ojo de matar a un ni\u00f1o que ha matado?"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_9183\" aria-describedby=\"caption-attachment-9183\" style=\"width: 644px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9183 size-large\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Oscuridad-644x429.jpg\" alt=\"\" width=\"644\" height=\"429\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Oscuridad-644x429.jpg 644w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Oscuridad-300x200.jpg 300w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Oscuridad-768x512.jpg 768w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Oscuridad.jpg 1350w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><figcaption id=\"caption-attachment-9183\" class=\"wp-caption-text\">Foto: Ferm\u00edn Rodr\u00edguez<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. Creo que el hecho de que no exista la pena de muerte en Espa\u00f1a nos hace mejores a todos. Es un signo de civilizaci\u00f3n y hasta de educaci\u00f3n me atrever\u00eda a decir. Pero no soy un ingenuo y s\u00e9 que hay personas que defienden el &#8216;ojo por ojo&#8217;, dar de su misma medicina a quien ha cometido un delito. La pregunta es: \u00bfSer\u00eda capaz quien defiende el ojo por ojo de matar a un ni\u00f1o que ha matado?<\/p>\n<p>Adem\u00e1s, ese ni\u00f1o que ha matado tambi\u00e9n puede ser nuestro hijo, no lo olvidemos.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. Creo que el hecho de que no exista la pena de muerte en Espa\u00f1a nos hace mejores a todos. Es un signo de civilizaci\u00f3n y hasta de educaci\u00f3n me atrever\u00eda a decir. Pero no soy un ingenuo y s\u00e9 que hay personas que defienden el &#8216;ojo por ojo&#8217;, dar de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[719,2977],"class_list":["post-15139","post","type-post","status-publish","format-standard","hentry","category-blog","tag-matar","tag-ojo-por-ojo"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-3Wb","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/15139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=15139"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/15139\/revisions"}],"predecessor-version":[{"id":15142,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/15139\/revisions\/15142"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=15139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=15139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=15139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}