{"id":14623,"date":"2021-04-25T20:16:55","date_gmt":"2021-04-25T18:16:55","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=14623"},"modified":"2021-04-25T20:16:55","modified_gmt":"2021-04-25T18:16:55","slug":"don-emilio-en-la-cope-no-me-gusta-que-los-partidos-politicos-utilicen-mis-opiniones","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2021\/04\/don-emilio-en-la-cope-no-me-gusta-que-los-partidos-politicos-utilicen-mis-opiniones\/","title":{"rendered":"Don Emilio en la Cope: \u00abNo me gusta que los partidos pol\u00edticos utilicen mis opiniones\u00bb"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_13866\" aria-describedby=\"caption-attachment-13866\" style=\"width: 644px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13866 size-large\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/11\/Emilio-644x429.jpg\" alt=\"\" width=\"644\" height=\"429\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/11\/Emilio-644x429.jpg 644w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/11\/Emilio-300x200.jpg 300w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/11\/Emilio-768x512.jpg 768w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><figcaption id=\"caption-attachment-13866\" class=\"wp-caption-text\">Foto: Ram\u00f3n L. P\u00e9rez<\/p>\n<p><\/figcaption><\/figure>\n<p>Hola, soy Carlos Mor\u00e1n, el compa\u00f1ero de blog de don Emilio y, sin embargo, amigo. El juez participa los domingos por la ma\u00f1ana en el programa de la cadena Cope que dirige la periodista\u00a0Cristina L\u00f3pez Schlichting. En su intervenci\u00f3n de hoy, y entre otras cosas, ha vuelto a hablar de los ni\u00f1os de las pateras y del desagrado que le produce que haya quien use, cambiando el sentido,\u00a0 lo que dice para hacer pol\u00edtica. \u00abNo me gusta que los partidos pol\u00edticos utilicen mis opiniones. Para eso me habr\u00eda metido yo en pol\u00edtica, pero no soy pol\u00edtico. Soy un padre, un ciudadano y un juez penal\u00bb.<\/p>\n<p>Adem\u00e1s, volvi\u00f3 a reiterar lo que dijo aqu\u00ed en el blog: que el dinero que se emplea en recuperar a los chavales que delinquen est\u00e1 muy bien empleado y que \u00ablos ni\u00f1os no tienen precio\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Hola, soy Carlos Mor\u00e1n, el compa\u00f1ero de blog de don Emilio y, sin embargo, amigo. El juez participa los domingos por la ma\u00f1ana en el programa de la cadena Cope que dirige la periodista\u00a0Cristina L\u00f3pez Schlichting. En su intervenci\u00f3n de hoy, y entre otras cosas, ha vuelto a hablar de los ni\u00f1os de las [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[2886,12,428],"class_list":["post-14623","post","type-post","status-publish","format-standard","hentry","category-blog","tag-cope","tag-don-emilio","tag-politicos"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-3NR","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/14623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=14623"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/14623\/revisions"}],"predecessor-version":[{"id":14624,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/14623\/revisions\/14624"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=14623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=14623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=14623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}