{"id":14119,"date":"2021-01-08T21:04:22","date_gmt":"2021-01-08T19:04:22","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=14119"},"modified":"2021-01-08T21:04:22","modified_gmt":"2021-01-08T19:04:22","slug":"la-primera-en-la-frente-sube-la-luz-cuando-estamos-helaicos-de-frio-y-en-plena-crisis","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2021\/01\/la-primera-en-la-frente-sube-la-luz-cuando-estamos-helaicos-de-frio-y-en-plena-crisis\/","title":{"rendered":"La primera, en la frente: sube la luz cuando estamos &#8216;hela\u00edcos&#8217; de fr\u00edo y en plena crisis"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_9183\" aria-describedby=\"caption-attachment-9183\" style=\"width: 644px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9183 size-large\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Oscuridad-644x429.jpg\" alt=\"\" width=\"644\" height=\"429\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Oscuridad-644x429.jpg 644w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Oscuridad-300x200.jpg 300w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Oscuridad-768x512.jpg 768w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/09\/Oscuridad.jpg 1350w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><figcaption id=\"caption-attachment-9183\" class=\"wp-caption-text\">Foto: Ferm\u00edn Rodr\u00edguez<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. El a\u00f1o 2021 est\u00e1n teniendo un inicio prometedor (es iron\u00eda y sarcasmo): un &#8216;tejerazo&#8217; en Estados Unidos y a la manera de Estados Unidos, y una subida de\u00a0 luz a la espa\u00f1ola. La primera, en la frente: sube el precio de la electricidad cuando estamos &#8216;hela\u00edcos&#8217; de fr\u00edo y en plena crisis econ\u00f3mico. \u00bfPor que seguimos pagando un IVA del 21%, como si fuera un lujo, en lugar de uno reducido como corresponde a un art\u00edculo de primera necesidad? Ni idea.<\/p>\n<p>Un recuerdo para todos los vecinos de Granada que llevan a\u00f1os soportando cortes de luz. Que no paguen justos por pecadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. El a\u00f1o 2021 est\u00e1n teniendo un inicio prometedor (es iron\u00eda y sarcasmo): un &#8216;tejerazo&#8217; en Estados Unidos y a la manera de Estados Unidos, y una subida de\u00a0 luz a la espa\u00f1ola. La primera, en la frente: sube el precio de la electricidad cuando estamos &#8216;hela\u00edcos&#8217; de fr\u00edo y en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[614,469,2807],"class_list":["post-14119","post","type-post","status-publish","format-standard","hentry","category-blog","tag-luz","tag-precio","tag-subida"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-3FJ","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/14119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=14119"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/14119\/revisions"}],"predecessor-version":[{"id":14121,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/14119\/revisions\/14121"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=14119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=14119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=14119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}