{"id":13942,"date":"2020-12-05T20:58:18","date_gmt":"2020-12-05T18:58:18","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=13942"},"modified":"2020-12-05T20:58:18","modified_gmt":"2020-12-05T18:58:18","slug":"si-llevais-anos-sin-hablaros-con-un-familiar-la-nochebuena-que-viene-es-la-menos-indicada-para-juntaros-y-arreglarlo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2020\/12\/si-llevais-anos-sin-hablaros-con-un-familiar-la-nochebuena-que-viene-es-la-menos-indicada-para-juntaros-y-arreglarlo\/","title":{"rendered":"Si llev\u00e1is a\u00f1os sin hablaros con un familiar, la Nochebuena que viene es la menos indicada para juntaros y arreglarlo"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_13210\" aria-describedby=\"caption-attachment-13210\" style=\"width: 644px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13210 size-large\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/07\/Emil-nueva-1-644x429.jpg\" alt=\"\" width=\"644\" height=\"429\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/07\/Emil-nueva-1-644x429.jpg 644w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/07\/Emil-nueva-1-300x200.jpg 300w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/07\/Emil-nueva-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><figcaption id=\"caption-attachment-13210\" class=\"wp-caption-text\">FOTO: PEPE MAR\u00cdN<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. Creo que igual se debe a la &#8216;malafoll\u00e1 grana\u00edna&#8217;, pero me consta que hay familiares o allegados, sea eso lo que quiera que sea, que llevan a\u00f1os sin hablarse pero que est\u00e1n quedando para juntarse precisamente esta Navidad de 2020. \u00a1Por favor, que digo yo que habr\u00e1s m\u00e1s a\u00f1os para arreglar las desavenencias familiares! La Nochebuena o la Nochevieja que vienen son las menos indicadas de la historia de las Nochebuenas y las Nocheviejas para juntarse. Seamos serios. Que la pandemia no da risa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. Creo que igual se debe a la &#8216;malafoll\u00e1 grana\u00edna&#8217;, pero me consta que hay familiares o allegados, sea eso lo que quiera que sea, que llevan a\u00f1os sin hablarse pero que est\u00e1n quedando para juntarse precisamente esta Navidad de 2020. \u00a1Por favor, que digo yo que habr\u00e1s m\u00e1s a\u00f1os para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[2790,2791,2288],"class_list":["post-13942","post","type-post","status-publish","format-standard","hentry","category-blog","tag-desavenencias","tag-familiares","tag-nochebuena"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-3CS","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/13942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=13942"}],"version-history":[{"count":7,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/13942\/revisions"}],"predecessor-version":[{"id":13949,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/13942\/revisions\/13949"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=13942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=13942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=13942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}