{"id":13186,"date":"2020-07-25T20:05:56","date_gmt":"2020-07-25T18:05:56","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=13186"},"modified":"2020-07-25T20:05:56","modified_gmt":"2020-07-25T18:05:56","slug":"consejos-para-criar-a-un-contagiador-si-el-nino-esta-siempre-de-fiesta-y-los-abuelos-no-quieren-verlo-renid-a-los-abuelos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2020\/07\/consejos-para-criar-a-un-contagiador-si-el-nino-esta-siempre-de-fiesta-y-los-abuelos-no-quieren-verlo-renid-a-los-abuelos\/","title":{"rendered":"Consejos para criar a un contagiador: Si el ni\u00f1o est\u00e1 siempre de fiesta y los abuelos no quieren verlo, re\u00f1id a los abuelos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_12792\" aria-describedby=\"caption-attachment-12792\" style=\"width: 644px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12792 size-large\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/05\/Nueva-dos-644x429.jpg\" alt=\"\" width=\"644\" height=\"429\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/05\/Nueva-dos-644x429.jpg 644w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/05\/Nueva-dos-300x200.jpg 300w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/05\/Nueva-dos-768x512.jpg 768w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2020\/05\/Nueva-dos.jpg 800w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><figcaption id=\"caption-attachment-12792\" class=\"wp-caption-text\">Foto: Pepe Mar\u00edn<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. Tras publicar por en\u00e9sima vez el dec\u00e1logo para criar a un delincuente, Carlos y yo estuvimos charlando y nos salieron unos consejos para criar a un contagiador de coronavirus. Esperamos que nadie los siga, claro.<\/p>\n<p>Si el ni\u00f1o est\u00e1 siempre de fiesta, sale todas las noches y los abuelos no quieren verlo para no correr riesgos, re\u00f1id a los abuelos. Eso har\u00e1n que, adem\u00e1s de lo que ya tienen encima, se sientan culpables.<\/p>\n<p>Si a tu hijo le multan por no llevar puesta la mascarilla, ve a quejarte a voces a la Polic\u00eda y que el ni\u00f1o te acompa\u00f1e para que aprenda que no hay que respetar a la autoridad.<\/p>\n<p>Y si tu hijo se contagia, \u00e9chale la culpa a sus amigos y den\u00fancialos a todos. Que aprenda que los responsables de lo que \u00e9l hace, y vosotros le dej\u00e1is hacer, siempre son los dem\u00e1s.<\/p>\n<p>Si segu\u00eds estas recomendaciones, los que se\u00e1is cat\u00f3licos, rezad y los que no, invocad a las energ\u00edas positivas. Os va a hacer falta.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. Tras publicar por en\u00e9sima vez el dec\u00e1logo para criar a un delincuente, Carlos y yo estuvimos charlando y nos salieron unos consejos para criar a un contagiador de coronavirus. Esperamos que nadie los siga, claro. Si el ni\u00f1o est\u00e1 siempre de fiesta, sale todas las noches y los abuelos no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[91,2709,2708],"class_list":["post-13186","post","type-post","status-publish","format-standard","hentry","category-blog","tag-consejos","tag-contagiador","tag-criar"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-3qG","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/13186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=13186"}],"version-history":[{"count":8,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/13186\/revisions"}],"predecessor-version":[{"id":13194,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/13186\/revisions\/13194"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=13186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=13186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=13186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}