{"id":1247,"date":"2011-04-24T16:45:52","date_gmt":"2011-04-24T15:45:52","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=1247"},"modified":"2011-04-24T16:45:52","modified_gmt":"2011-04-24T15:45:52","slug":"la-familia-debe-ser-la-primera-linea-de-proteccion-de-los-menores-frente-a-la-television-e-internet","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2011\/04\/la-familia-debe-ser-la-primera-linea-de-proteccion-de-los-menores-frente-a-la-television-e-internet\/","title":{"rendered":"La familia debe ser la primera l\u00ednea de protecci\u00f3n de los menores frente a la televisi\u00f3n e Internet"},"content":{"rendered":"<p>El \u00faltimo informe del Defensor del Pueblo nacional dedica un extenso apartado a hablar de la creciente influencia de los medios audiovisuales en la sociedad y, en especial, en los menores. Tras el an\u00e1lisis, formula una serie de sencillos pero \u00fatiles recomendaciones. Esperamos que os sirvan. \u00abLa primera es la necesidad de que las familias tomen conciencia real del tiempo que sus hijos dedican a la televisi\u00f3n e internet y limitarlo proponiendo a sus hijos alternativas de ocio.Tambi\u00e9n se propone a las familias adecuar los horarios de consumo a los apropiados a la edad y cuando este consumo se produce fuera del horario protegido, se recomienda que se informen sobre la programaci\u00f3n para valorar si \u00e9sta es adecuada para los menores.<\/p>\n<p>\u00a0<\/p>\n<p>En la medida de lo posible es conveniente que los receptores de televisi\u00f3n y los ordenadores est\u00e9n en zonas comunes del hogar para evitar el consumo solitario y en todo caso debe fomentarse el uso com\u00fan y familiar de estos medios. Los padres deben informarse y aplicar los controles de car\u00e1cter parental disponibles, utilizar filtros y programas de control para el acceso a determinados contenidos de internet y alertar a los menores sobre los riesgos de estos medios, todo lo cual exige interesarse por las nuevas tecnolog\u00edas para superar la brecha digital que a menudo existe entre ellos y sus hijos.<\/p>\n<p>Estas y otras medidas elementales son imprescindibles para proteger a los menores en esa primera l\u00ednea de acci\u00f3n que es el hogar y la familia\u00bb.<\/p>\n<p>M\u00e1s informaci\u00f3n: <a href=\"http:\/\/www.defensordelpueblo.es\/es\/Documentacion\/Publicaciones\/anual\/Documentos\/InformeAnualCortesGenerales2010.pdf\">http:\/\/www.defensordelpueblo.es\/es\/Documentacion\/Publicaciones\/anual\/Documentos\/InformeAnualCortesGenerales2010.pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u00faltimo informe del Defensor del Pueblo nacional dedica un extenso apartado a hablar de la creciente influencia de los medios audiovisuales en la sociedad y, en especial, en los menores. Tras el an\u00e1lisis, formula una serie de sencillos pero \u00fatiles recomendaciones. Esperamos que os sirvan. \u00abLa primera es la necesidad de que las familias [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1247","post","type-post","status-publish","format-standard","hentry","category-blog"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-k7","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/1247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=1247"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/1247\/revisions"}],"predecessor-version":[{"id":1249,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/1247\/revisions\/1249"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=1247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=1247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=1247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}