{"id":1173,"date":"2011-03-13T21:17:32","date_gmt":"2011-03-13T20:17:32","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=1173"},"modified":"2011-03-13T21:17:32","modified_gmt":"2011-03-13T20:17:32","slug":"los-casos-de-hijos-que-maltratan-a-sus-padres-se-han-duplicado-en-apenas-tres-anos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2011\/03\/los-casos-de-hijos-que-maltratan-a-sus-padres-se-han-duplicado-en-apenas-tres-anos\/","title":{"rendered":"Los casos de hijos que maltratan a sus padres se han duplicado en apenas tres a\u00f1os"},"content":{"rendered":"<p>Los hijos que pegan a sus padres es un tema que ha estado presente en este blog pr\u00e1cticamente desde que se abri\u00f3. Hay varios &#8216;post&#8217; dedicados a ese asunto. Aqu\u00ed va uno m\u00e1s que certifica con estad\u00edsticas oficiales que el fen\u00f3meno va a m\u00e1s, lo cual -y esto tambi\u00e9n lo hemos dicho en varias ocasiones- no es necesariamente malo: puede significar que se denuncia m\u00e1s, que es el primer paso para solucionar un problema que solo el que lo padece sabe los duro que es. Bueno, aqu\u00ed os dejamos la informaci\u00f3n.<\/p>\n<p>\u00abLas fiscal\u00edas de Menores abrieron en 2009 5.201 procedimientos por maltrato de hijos a\u00a0padres,\u00a0frente a los 4.211 de 2008 y a las 2.683 causas de 2007. Es decir, que estos casos se han duplicado en apenas tres a\u00f1os, seg\u00fan una informaci\u00f3n J. Luis \u00c1lvarez para la agencia Colpisa. Para Jos\u00e9 Miguel de la Rosa, fiscal de Menores, \u00abest\u00e1 claro que hay una crisis del principio de autoridad\u00bb en la familia, \u00ablo que hace que algo que hace quince a\u00f1os era impensable, que los hijos pegaran a los padres, ahora desgraciadamente no es impensable sino que a\u00f1o tras a\u00f1o se incrementa\u00bb. La propia Fiscal\u00eda General del Estado se vio obligada a dictar una circular sobre c\u00f3mo hab\u00eda que abordar este fen\u00f3meno \u00abque es relativamente nuevo\u00bb. Para De la Rosa el origen de estos abusos de los j\u00f3venes hacia sus mayores puede estar en un \u00abd\u00e9ficit educativo\u00bb. \u00abEn muchos casos no se ha ejercido la autoridad paterna de la forma adecuada. Hay una disciplina relajada en casa, ha habido demasiada permisibilidad y entonces llega un momento en que se produce la agresi\u00f3n\u00bb, dice\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los hijos que pegan a sus padres es un tema que ha estado presente en este blog pr\u00e1cticamente desde que se abri\u00f3. Hay varios &#8216;post&#8217; dedicados a ese asunto. Aqu\u00ed va uno m\u00e1s que certifica con estad\u00edsticas oficiales que el fen\u00f3meno va a m\u00e1s, lo cual -y esto tambi\u00e9n lo hemos dicho en varias ocasiones- [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1173","post","type-post","status-publish","format-standard","hentry","category-blog"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-iV","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/1173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=1173"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/1173\/revisions"}],"predecessor-version":[{"id":1175,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/1173\/revisions\/1175"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=1173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=1173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=1173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}