{"id":11533,"date":"2019-10-16T19:55:50","date_gmt":"2019-10-16T17:55:50","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=11533"},"modified":"2019-10-16T19:55:50","modified_gmt":"2019-10-16T17:55:50","slug":"el-baloncesto-espanol-luchara-contra-el-acoso-escolar-bien-ahora-que-rechacen-el-patrocinio-de-las-casas-de-apuestas","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2019\/10\/el-baloncesto-espanol-luchara-contra-el-acoso-escolar-bien-ahora-que-rechacen-el-patrocinio-de-las-casas-de-apuestas\/","title":{"rendered":"El baloncesto espa\u00f1ol luchar\u00e1 contra el acoso escolar, \u00a1bien!, ahora que rechacen el patrocinio de las casas de apuestas"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-11129 size-large\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/08\/Emil-avisa-644x362.jpg\" alt=\"\" width=\"644\" height=\"362\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/08\/Emil-avisa-644x362.jpg 644w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/08\/Emil-avisa-300x169.jpg 300w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/08\/Emil-avisa.jpg 660w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/>La ACB, es decir, el baloncesto espa\u00f1ol, va a iniciar una campa\u00f1a para luchar contra la lacra del acoso escolar. \u00a1Bien! \u00a1Muy bien! Es muy importante que las estrellas del deporte se comprometan a combatir y prevenir una conducta delictiva como el matonismo en los centros escolares. Por la notoriedad p\u00fablica de los jugadores y su influencia entre los ni\u00f1os y los j\u00f3venes, seguro que contribuye a atajar este grave problema.<\/p>\n<p>Si ya aprovechase la ACB para rechazar el patrocinio de las casas de apuestas, la jugada ser\u00eda de sobresaliente. Mientras tanto, se queda en un insuficiente alto. El otro d\u00eda hubo una manifestaci\u00f3n en Madrid en la que varios centenares de vecinos pidieron a las autoridades que se pusiera coto a los locales de apuesta que est\u00e1n proliferando en todas las ciudades. Alertaban de que el juego genera adicci\u00f3n y est\u00e1 causando los mismos estragos entre los j\u00f3venes que provoc\u00f3 la hero\u00edna en los a\u00f1os 80 del siglo pasado. Llevaban raz\u00f3n. Y como no actuemos, lo vamos a pagar.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La ACB, es decir, el baloncesto espa\u00f1ol, va a iniciar una campa\u00f1a para luchar contra la lacra del acoso escolar. \u00a1Bien! \u00a1Muy bien! Es muy importante que las estrellas del deporte se comprometan a combatir y prevenir una conducta delictiva como el matonismo en los centros escolares. Por la notoriedad p\u00fablica de los jugadores [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[97,2429,648],"class_list":["post-11533","post","type-post","status-publish","format-standard","hentry","category-blog","tag-acoso","tag-apuestas","tag-escolar"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-301","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/11533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=11533"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/11533\/revisions"}],"predecessor-version":[{"id":11536,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/11533\/revisions\/11536"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=11533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=11533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=11533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}