{"id":11060,"date":"2019-07-26T20:04:08","date_gmt":"2019-07-26T18:04:08","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=11060"},"modified":"2019-07-27T20:30:18","modified_gmt":"2019-07-27T18:30:18","slug":"los-jefes-de-los-partidos-incumplen-su-deberes-y-sus-diputados-les-aplauden-moraleja-si-tu-hijo-suspende-aplaudele","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2019\/07\/los-jefes-de-los-partidos-incumplen-su-deberes-y-sus-diputados-les-aplauden-moraleja-si-tu-hijo-suspende-aplaudele\/","title":{"rendered":"Los jefes de los partidos incumplen sus deberes y sus diputados les aplauden; moraleja: si t\u00fa hijo suspende, apl\u00e1udele"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_10140\" aria-describedby=\"caption-attachment-10140\" style=\"width: 644px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10140 size-large\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/02\/Emil-1-644x428.jpg\" alt=\"\" width=\"644\" height=\"428\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/02\/Emil-1-644x428.jpg 644w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/02\/Emil-1-300x200.jpg 300w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/02\/Emil-1-768x511.jpg 768w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><figcaption id=\"caption-attachment-10140\" class=\"wp-caption-text\">Foto: Juan de Dios Ortiz<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. Los jefes de los distintos partidos no han cumplido con su deber de formar un gobierno, pero sus subordinados (los diputados rasos) les aplauden a rabiar en el Congreso. Moraleja: si tu hijo suspende, apl\u00e1udele, y si suspende todo, ovaci\u00f3n al canto.<\/p>\n<p>Esas son las lecciones que nos transmiten nuestros pol\u00edticos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. Los jefes de los distintos partidos no han cumplido con su deber de formar un gobierno, pero sus subordinados (los diputados rasos) les aplauden a rabiar en el Congreso. Moraleja: si tu hijo suspende, apl\u00e1udele, y si suspende todo, ovaci\u00f3n al canto. Esas son las lecciones que nos transmiten nuestros [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[189,2444,428],"class_list":["post-11060","post","type-post","status-publish","format-standard","hentry","category-blog","tag-hijos","tag-moraleja","tag-politicos"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-2So","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/11060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=11060"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/11060\/revisions"}],"predecessor-version":[{"id":11069,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/11060\/revisions\/11069"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=11060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=11060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=11060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}