{"id":11042,"date":"2019-07-22T20:22:13","date_gmt":"2019-07-22T18:22:13","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=11042"},"modified":"2019-07-22T20:22:13","modified_gmt":"2019-07-22T18:22:13","slug":"aunque-me-llamen-malatayu-he-llegado-a-sentir-carino-por-muchos-de-mis-choricillos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2019\/07\/aunque-me-llamen-malatayu-he-llegado-a-sentir-carino-por-muchos-de-mis-choricillos\/","title":{"rendered":"Aunque me llamen &#8216;Malatay\u00fa&#8217;, he llegado a sentir cari\u00f1o por muchos de mis &#8216;choricillos&#8217;"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_8783\" aria-describedby=\"caption-attachment-8783\" style=\"width: 624px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8783 size-full\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/07\/cero-y-Emilio.jpg\" alt=\"\" width=\"624\" height=\"385\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/07\/cero-y-Emilio.jpg 624w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/07\/cero-y-Emilio-300x185.jpg 300w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><figcaption id=\"caption-attachment-8783\" class=\"wp-caption-text\">ideal.es<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. A lo largo de mi vida, he juzgado a miles de ni\u00f1os y adolescentes. \u00a1Miles! Ufff, es que ya voy &#8216;p&#8217;arriba&#8217;. Pues bien, y como ya es hora de ir haciendo balance (no es que no me vaya a jubilar todav\u00eda), puedo decir que he llegado a sentir cari\u00f1o por muchos de mis &#8216;choricillos&#8217;. Incluso dir\u00eda que por la mayor\u00eda de ellos. Igual os parece raro, pero es la verdad. Eso no quiere decir que me tiemble la mano a la hora de aplicar la ley: por algo me llaman &#8216;Malatay\u00fa&#8217;. Pero yo creo que es su forma de decirme que ellos tambi\u00e9n me quieren, ja, ja, ja.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. A lo largo de mi vida, he juzgado a miles de ni\u00f1os y adolescentes. \u00a1Miles! Ufff, es que ya voy &#8216;p&#8217;arriba&#8217;. Pues bien, y como ya es hora de ir haciendo balance (no es que no me vaya a jubilar todav\u00eda), puedo decir que he llegado a sentir cari\u00f1o por [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[1656,1021],"class_list":["post-11042","post","type-post","status-publish","format-standard","hentry","category-blog","tag-choricillos","tag-carino"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-2S6","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/11042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=11042"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/11042\/revisions"}],"predecessor-version":[{"id":11043,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/11042\/revisions\/11043"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=11042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=11042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=11042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}