{"id":10991,"date":"2019-07-14T20:25:15","date_gmt":"2019-07-14T18:25:15","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=10991"},"modified":"2019-07-14T20:26:02","modified_gmt":"2019-07-14T18:26:02","slug":"habra-manadas-mientras-siga-habiendo-padres-que-no-pongan-limites-a-los-hijos-ni-ejerzan-su-autoridad","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2019\/07\/habra-manadas-mientras-siga-habiendo-padres-que-no-pongan-limites-a-los-hijos-ni-ejerzan-su-autoridad\/","title":{"rendered":"Habr\u00e1 manadas mientras siga habiendo padres que no pongan l\u00edmites a los hijos ni ejerzan su autoridad"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_10140\" aria-describedby=\"caption-attachment-10140\" style=\"width: 644px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10140 size-large\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/02\/Emil-1-644x428.jpg\" alt=\"\" width=\"644\" height=\"428\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/02\/Emil-1-644x428.jpg 644w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/02\/Emil-1-300x200.jpg 300w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/02\/Emil-1-768x511.jpg 768w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><figcaption id=\"caption-attachment-10140\" class=\"wp-caption-text\">Foto: Juan de Dios Ortiz<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. Escucho que se ha producido otro presunto caso de una manada, es decir, de una pandilla de j\u00f3venes que est\u00e1n siendo investigados por haber agredido sexualmente a una menor de 17 a\u00f1os. No soy optimista. Creo que habr\u00e1 manadas mientras siga habiendo padres que no pongan l\u00edmites a los hijos ni ejerzan su autoridad, todo eso, claro est\u00e1, aderezado con cari\u00f1o y respeto, porque no solo de autoridad vive el hombre. Pero los l\u00edmites y la autoridad son imprescindibles. Sin alguien crece, lo repito siempre, sin que nadie le diga que sus derechos acaban donde empiezan los de los dem\u00e1s, es probable que acabe teniendo problemas con la ley.<\/p>\n<p>La autoridad es imprescindible para que una sociedad funcione. La mayor\u00eda no nos saltamos los sem\u00e1foros en rojo porque existe la autoridad. Pues en la familia debe pasar lo mismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. Escucho que se ha producido otro presunto caso de una manada, es decir, de una pandilla de j\u00f3venes que est\u00e1n siendo investigados por haber agredido sexualmente a una menor de 17 a\u00f1os. No soy optimista. Creo que habr\u00e1 manadas mientras siga habiendo padres que no pongan l\u00edmites a los hijos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[1803,2306],"class_list":["post-10991","post","type-post","status-publish","format-standard","hentry","category-blog","tag-limites","tag-manadas"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-2Rh","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/10991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=10991"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/10991\/revisions"}],"predecessor-version":[{"id":10994,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/10991\/revisions\/10994"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=10991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=10991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=10991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}