{"id":1062,"date":"2011-01-26T17:39:15","date_gmt":"2011-01-26T16:39:15","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=1062"},"modified":"2011-01-26T18:06:17","modified_gmt":"2011-01-26T17:06:17","slug":"justicia-si-cacerias-humanas-no","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2011\/01\/justicia-si-cacerias-humanas-no\/","title":{"rendered":"Justicia, s\u00ed, cacer\u00edas humanas, no"},"content":{"rendered":"<div><span lang=\"ES-MODERN\">Quiz\u00e1 sea una historia que muchos de vosotros ya conozc\u00e1is, porque ha tenido una notable repercusi\u00f3n medi\u00e1tica. El pasado fin de semana un ciudadano de Granada &#8216;colg\u00f3&#8217; en Internet un v\u00eddeo en el que varios j\u00f3venes propinaban una escalofriante paliza a otro joven. Ocurri\u00f3 en las puertas de una discoteca. Molesto porque, seg\u00fan \u00e9l, la Polic\u00eda y la Justicia no hab\u00edan hecho nada al respecto, el ciudadano present\u00f3 una denuncia -incluso parecen que son dos- por la agresi\u00f3n&#8230; y lo hizo p\u00fablico. Acto seguido, otro ciudadano tuvo la &#8216;brillant\u00edsima&#8217; idea de crear un grupo en &#8216;Faceboock&#8217; para que la gente que hubiese visto el v\u00eddeo denunciase a los agresores. Como era de esperar, la citada p\u00e1gina es un aut\u00e9ntico desastre\u00a0en el que abundan las\u00a0delaciones y las acusaciones sin pruebas. Varios de los participantes en ese grupo han se\u00f1alado directamente a una menor, lo que, a su vez, ha obligado a la Fiscal\u00eda de Menores a intervenir. He aqu\u00ed otra prueba evidente de que un mal uso de Internet y de las redes sociales no resuelve nada y s\u00f3lo sirve para crear problemas, cuando menos, tan graves como los que se pretend\u00edan denunciar.<\/span><\/div>\n<div><span lang=\"ES-MODERN\">No lo decimos nosotros: un lector del blog nos ha hecho llegar su oipin\u00f3n sobre este asunto.\u00a0Como a\u00f1ade\u00a0sensatez y sentido com\u00fan, reproducimos su comentario \u00edntegramente.<\/span><\/div>\n<p><span lang=\"ES-MODERN\">\u00abLe ruego publique tan pronto le sea posible alguna entrada en el blog comentando los sucesos que est\u00e1 viviendo la ciudad de Granada por causa del v\u00eddeo en donde un grupo de j\u00f3venes la emprende contra otro. Me refiero en concreto a la cacer\u00eda loca, sin sentido, irracional, que se ha desatado en esta ciudad, con ciudadanos reconvertidos en Charles Bronson aplicando su propia justicia al margen de la ley. Se ha puesto fin a la presunci\u00f3n de inocencia, se confunde sospechoso con culpable, se violan los derechos de terceros personas, se matan mosquitos a ca\u00f1onazos, se amenaza y coacciona a voluntad a terceros&#8230; Un comportamiento que s\u00f3lo puede ser descrito como ajustacimiento del populacho, en forma de una turba en Internet que justifica cualquier barrabasada para lograr un fin.<\/p>\n<p>La polic\u00eda, la fiscal\u00eda, los abogados, los jueces&#8230; todo ha quedado aparcado en nombre de unos comportamientos que se asemejan a una cacer\u00eda humana, en donde uno apunta, otros confirman y la multitud dispara, sin pruebas, sin juicio, sin derechos, sin raz\u00f3n ni l\u00f3gica.<\/p>\n<p>Lo m\u00e1s triste es comprobar la cantidad de bestias, aut\u00e9nticos garrulos urbanitas, que defienden estas pr\u00e1cticas y que defienden la justicia m\u00e1s animal y salvaje imaginable. El Oeste estadounidense ya parece un cuento de ni\u00f1os al lado de lo que estamos empezando a vivir. Y lo peor de todo es que ya existen antecedentes de estas pr\u00e1cticas tan peligrosas y sus consecuencias, pero todos parecen hacer o\u00eddos sordos.<\/p>\n<p>Se lo ruego, aporte algo de raz\u00f3n a lo que est\u00e1 sucediendo. Hoy me averg\u00fcenzo de vivir en esta ciudad\u00bb.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quiz\u00e1 sea una historia que muchos de vosotros ya conozc\u00e1is, porque ha tenido una notable repercusi\u00f3n medi\u00e1tica. El pasado fin de semana un ciudadano de Granada &#8216;colg\u00f3&#8217; en Internet un v\u00eddeo en el que varios j\u00f3venes propinaban una escalofriante paliza a otro joven. Ocurri\u00f3 en las puertas de una discoteca. Molesto porque, seg\u00fan \u00e9l, la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1062","post","type-post","status-publish","format-standard","hentry","category-blog"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-h8","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/1062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=1062"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/1062\/revisions"}],"predecessor-version":[{"id":1064,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/1062\/revisions\/1064"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=1062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=1062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=1062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}