{"id":1054,"date":"2011-01-18T18:45:08","date_gmt":"2011-01-18T17:45:08","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=1054"},"modified":"2011-01-18T18:45:50","modified_gmt":"2011-01-18T17:45:50","slug":"la-cara-oscura-de-internet","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2011\/01\/la-cara-oscura-de-internet\/","title":{"rendered":"La cara oscura de Internet"},"content":{"rendered":"<p class=\"resumeArcticle\" style=\"font-size: 13px;\">Son cosas que parece que s\u00f3lo ocurren en las pel\u00edculas, pero tambi\u00e9n suceden en la realidad. Internet es maravilloso, pero tambi\u00e9n tiene un lado oscuro (como la propia vida real). As\u00ed que como hacemos en la vida real hay que tomar precauciones. Nos evitaremos disgustos. Aqu\u00ed os dejamos un par de\u00a0noticias, una de Europa Press y otra de Efe,\u00a0que nos hablan de esa cara oscura de la red. \u00abLa Fiscal\u00eda de Madrid solicita trece a\u00f1os de prisi\u00f3n para un acusado de un delito de abusos sexuales y corrupci\u00f3n de menores por contactar con una ni\u00f1a a trav\u00e9s del Messenger de Internet y concertar citas en las que abusaba de la misma sin que \u00e9sta denunciara por miedo de que difundiera v\u00eddeos grabados en los encuentros. El fiscal pide para el procesado, de 32 a\u00f1os, nueve a\u00f1os de c\u00e1rcel por un delito continuado de abusos sexuales y cuatro a\u00f1os por un delito continuado de corrupci\u00f3n de menores\u00bb.<\/p>\n<p class=\"resumeArcticle\" style=\"font-size: 13px;\">\u00a0\u00abUn joven vizca\u00edno de 21 a\u00f1os ha ingresado en prisi\u00f3n preventiva por un delito de corrupci\u00f3n de menores, tras haber sido acusado de usurpar la identidad en la red e inducir a decenas de ni\u00f1as y j\u00f3venes mediante enga\u00f1os, amenazas y coacciones, a quitarse la ropa ante las c\u00e1maras de sus ordenadores y grabarlas\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Son cosas que parece que s\u00f3lo ocurren en las pel\u00edculas, pero tambi\u00e9n suceden en la realidad. Internet es maravilloso, pero tambi\u00e9n tiene un lado oscuro (como la propia vida real). As\u00ed que como hacemos en la vida real hay que tomar precauciones. Nos evitaremos disgustos. Aqu\u00ed os dejamos un par de\u00a0noticias, una de Europa Press [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1054","post","type-post","status-publish","format-standard","hentry","category-blog"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-h0","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/1054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=1054"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/1054\/revisions"}],"predecessor-version":[{"id":1056,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/1054\/revisions\/1056"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=1054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=1054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=1054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}