{"id":10078,"date":"2019-02-05T21:44:08","date_gmt":"2019-02-05T19:44:08","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=10078"},"modified":"2019-02-05T21:55:52","modified_gmt":"2019-02-05T19:55:52","slug":"un-padre-pierde-la-custodia-de-sus-hijos-por-fumador-que-se-haga-tambien-con-los-padres-adictos-al-movil","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2019\/02\/un-padre-pierde-la-custodia-de-sus-hijos-por-fumador-que-se-haga-tambien-con-los-padres-adictos-al-movil\/","title":{"rendered":"Un padre pierde la custodia de sus hijos por fumador; que se haga tambi\u00e9n con los padres adictos al m\u00f3vil"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9067 size-full\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/08\/emilio-calatayud.jpg\" alt=\"\" width=\"624\" height=\"385\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/08\/emilio-calatayud.jpg 624w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/08\/emilio-calatayud-300x185.jpg 300w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/>Buenas, soy Emilio Calatayud. La Audiencia de C\u00f3rdoba ha dictado una novedosa sentencia en la que retira la custodia compartida de sus hijos a un padre que era un fumador empedernido. Dice el tribunal con gran sentido com\u00fan que el hombre antepone su adicci\u00f3n a la salud de sus dos hijos, a los que los jueces tambi\u00e9n escucharon para adoptar una decisi\u00f3n que, en mi opini\u00f3n, es muy acertada.<\/p>\n<p>Ahora se deber\u00eda aplicar esta misma soluci\u00f3n a los padres y madres que est\u00e1n todo el d\u00eda pendientes del m\u00f3vil, que son adictos al m\u00f3vil. Y tambi\u00e9n a esos padres que regalan una tablet o un m\u00f3vil a sus hijos para que no molesten y les dejen a ellos estar pendientes de sus guasap.<\/p>\n<p>Siempre lo digo, yo he fumado como una chimenea, pero no se me ocurri\u00f3 darle un cigarrillo a mi hijo cuando ten\u00eda cuatro o cinco a\u00f1os (tampoco despu\u00e9s). Pues con los m\u00f3viles se est\u00e1 haciendo. Y son una droga.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. La Audiencia de C\u00f3rdoba ha dictado una novedosa sentencia en la que retira la custodia compartida de sus hijos a un padre que era un fumador empedernido. Dice el tribunal con gran sentido com\u00fan que el hombre antepone su adicci\u00f3n a la salud de sus dos hijos, a los que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[1046,1801,663],"class_list":["post-10078","post","type-post","status-publish","format-standard","hentry","category-blog","tag-custodia","tag-fumador","tag-movil"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-2Cy","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/10078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=10078"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/10078\/revisions"}],"predecessor-version":[{"id":10081,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/10078\/revisions\/10081"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=10078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=10078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=10078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}